{"id":4048,"date":"2026-07-14T16:54:14","date_gmt":"2026-07-14T16:54:14","guid":{"rendered":"https:\/\/thepeople.mx\/index.php\/2026\/07\/14\/trump-finalmente-paga-5-6-millones-a-e-jean-carroll-tras-anos-de-dilacion\/"},"modified":"2026-07-14T22:54:16","modified_gmt":"2026-07-14T22:54:16","slug":"trump-finalmente-paga-5-6-millones-a-e-jean-carroll-tras-anos-de-dilacion","status":"publish","type":"post","link":"https:\/\/thepeople.mx\/index.php\/2026\/07\/14\/trump-finalmente-paga-5-6-millones-a-e-jean-carroll-tras-anos-de-dilacion\/","title":{"rendered":"Trump finalmente paga 5.6 millones a E. Jean Carroll tras a\u00f1os de dilaci\u00f3n"},"content":{"rendered":"<p>Despu\u00e9s de m\u00e1s de tres a\u00f1os de batalla legal, el expresidente Donald Trump tuvo que desembolsar este martes 14 de julio de 2026 m\u00e1s de 5.6 millones de d\u00f3lares a la escritora neoyorquina E. Jean Carroll, como resultado de un juicio civil que lo declar\u00f3 responsable de abuso sexual y difamaci\u00f3n.<\/p>\n<p>La cifra incluye el monto original de 5 millones de d\u00f3lares que un jurado civil de Manhattan le otorg\u00f3 a Carroll en 2023, m\u00e1s los intereses acumulados durante el prolongado proceso. Este pago se realiz\u00f3 tras una orden judicial del 8 de julio, cuando el juez Lewis A. Kaplan, nombrado por Bill Clinton, sentenci\u00f3 que Trump deb\u00eda \u201chacer justicia\u201d y dejar de retrasar el caso.<\/p>\n<p>El camino no fue sencillo: el 29 de junio, la Corte Suprema de Estados Unidos decidi\u00f3 no revisar la apelaci\u00f3n de Trump, lo que abri\u00f3 la puerta para que Carroll solicitara el pago inmediato. Trump intent\u00f3 resistirse, pero finalmente los fondos que \u00e9l hab\u00eda tenido que retener mientras segu\u00eda con su apelaci\u00f3n fueron liberados este martes.<\/p>\n<p>La demanda de Carroll se basa en un episodio ocurrido en la d\u00e9cada de 1990, cuando acus\u00f3 a Trump de agredirla sexualmente en un probador de una tienda departamental. Adem\u00e1s, en 2022, Trump atac\u00f3 p\u00fablicamente su reputaci\u00f3n calificando sus acusaciones como un \u201cenga\u00f1o\u201d, lo que deriv\u00f3 en la demanda por difamaci\u00f3n.<\/p>\n<p>Pero esta no es la \u00fanica batalla legal entre ambos. En 2024, otro jurado civil de Manhattan conden\u00f3 a Trump a pagar 83.3 millones de d\u00f3lares por difamaci\u00f3n, tras concluir que el expresidente la calumni\u00f3 en 2019 al negar por primera vez sus acusaciones. Esa apelaci\u00f3n sigue en curso.<\/p>\n<p>Este caso es un recordatorio de c\u00f3mo el poder y la impunidad pueden intentar silenciar a las v\u00edctimas, pero tambi\u00e9n de que la justicia, aunque lenta, puede abrirse paso. Mientras tanto, la sociedad sigue observando c\u00f3mo se manejan estas responsabilidades, y c\u00f3mo las estructuras legales responden a quienes est\u00e1n acostumbrados a evadirlas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de m\u00e1s de tres a\u00f1os de batalla legal, el expresidente Donald Trump tuvo que desembolsar este martes 14 de julio de 2026 m\u00e1s de 5.6 millones de d\u00f3lares a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4047,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-background","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/posts\/4048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4048"}],"version-history":[{"count":1,"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/posts\/4048\/revisions"}],"predecessor-version":[{"id":4049,"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/posts\/4048\/revisions\/4049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/media\/4047"}],"wp:attachment":[{"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thepeople.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}